{"id":8596,"date":"2021-02-24T12:24:46","date_gmt":"2021-02-24T12:24:46","guid":{"rendered":"https:\/\/lipotrue.com\/?page_id=8596"},"modified":"2021-02-24T12:25:53","modified_gmt":"2021-02-24T12:25:53","slug":"politica-de-cookies","status":"publish","type":"page","link":"https:\/\/lipotrue.com\/es\/politica-de-cookies\/","title":{"rendered":"Pol\u00edtica de cookies"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1552641277170{background-image: url(https:\/\/lipotrue.com\/wp-content\/uploads\/2019\/03\/area_privada_fondo05.jpg?id=1409) !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;4444&#8243; img_size=&#8221;full&#8221; alignment=&#8221;right&#8221; el_class=&#8221;iconos_lipotrue_web&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;3\/4&#8243;][vc_column_text]<\/p>\n<h2>Pol\u00edtica de cookies<\/h2>\n<p><span style=\"color: #002f5f;\">Informaci\u00f3n conforme a la normativa sobre cookies<\/span>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1552490080810{margin-top: 25px !important;background-color: #ffffff !important;}&#8221;][vc_column width=&#8221;1\/4&#8243; css=&#8221;.vc_custom_1552461786365{margin-top: 30px !important;margin-bottom: 30px !important;padding-top: 0px !important;padding-right: 0px !important;padding-bottom: 0px !important;}&#8221; el_class=&#8221;tech_marine_texto&#8221;][vc_single_image image=&#8221;4179&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;right&#8221; css=&#8221;.vc_custom_1552646805723{margin-bottom: 10px !important;}&#8221; el_class=&#8221;.tech_piedefoto&#8221;][\/vc_column][vc_column width=&#8221;3\/4&#8243;][vc_column_text css=&#8221;.vc_custom_1571826372537{margin-bottom: 6px !important;}&#8221;]<\/p>\n<h3 class=\"font_3\" style=\"text-align: left; font-size: 19px;\">Pol\u00edtica de cookies<\/h3>\n<p>[\/vc_column_text][vc_separator color=&#8221;green&#8221; align=&#8221;align_left&#8221; el_width=&#8221;50&#8243; css=&#8221;.vc_custom_1552461544079{margin-bottom: 10px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1614169545897{margin-bottom: 12px !important;}&#8221;]\n<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document cookie-statement cmplz-document-eu\"><p><i>Esta pol\u00edtica de cookies fue actualizada por \u00faltima vez el enero 8, 2026 y se aplica a los ciudadanos y residentes legales permanentes del Espacio Econ\u00f3mico Europeo y Suiza.<\/i><br><\/p><h2>1. Introducci\u00f3n<\/h2><p>Nuestra web, <a href=\"https:\/\/lipotrue.com\/es\/\">https:\/\/lipotrue.com\/es\/<\/a> (en adelante: \u00abla web\u00bb) utiliza cookies y otras tecnolog\u00edas relacionadas (para mayor comodidad, todas las tecnolog\u00edas se denominan \u00abcookies\u00bb). Las cookies tambi\u00e9n son colocadas por terceros a los que hemos contratado. En el siguiente documento te informamos sobre el uso de cookies en nuestra web.<\/p><h2>2. \u00bfQu\u00e9 son las cookies?<\/h2><p>Una cookie es un peque\u00f1o archivo que se env\u00eda junto con las p\u00e1ginas de esta web y que tu navegador almacena en el disco duro de su ordenador u otro dispositivo. La informaci\u00f3n almacenada puede ser devuelta a nuestros servidores o a los servidores de terceros apropiados durante una visita posterior.<\/p><h2>3. \u00bfQu\u00e9 son los scripts?<\/h2><p>Un script es un fragmento de c\u00f3digo de programa que se utiliza para hacer que nuestra web funcione correctamente y de forma interactiva. Este c\u00f3digo se ejecuta en nuestro servidor o en tu dispositivo.<\/p><h2>4. \u00bfQu\u00e9 es una baliza web?<\/h2><p>Una baliza web (o una etiqueta de p\u00edxel) es una peque\u00f1a e invisible pieza de texto o imagen en una web que se utiliza para monitorear el tr\u00e1fico en una web. Para ello, se almacenan varios datos sobre usted mediante estas balizas web.<\/p><h2>5. Cookies<\/h2><p class=\"cmplz-subtitle\">5.1 Cookies t\u00e9cnicas o funcionales<\/p><p>Algunas cookies aseguran que ciertas partes de la web funcionen correctamente y que tus preferencias de usuario sigan record\u00e1ndose. Al colocar cookies funcionales, te facilitamos la visita a nuestra web. De esta manera, no necesitas introducir repetidamente la misma informaci\u00f3n cuando visitas nuestra web y, por ejemplo, los art\u00edculos permanecen en tu cesta de la compra hasta que hayas pagado. Podemos colocar estas cookies sin tu consentimiento.<\/p><p class=\"cmplz-subtitle\">5.2 Cookies de estad\u00edsticas<\/p><p>Utilizamos cookies estad\u00edsticas para optimizar la experiencia de la web para nuestros usuarios. Con estas cookies estad\u00edsticas obtenemos informaci\u00f3n sobre el uso de nuestra web.&nbsp;Te pedimos tu permiso para colocar cookies de estad\u00edsticas.<\/p><p class=\"cmplz-subtitle\">5.3 Cookies de marketing\/seguimiento<\/p><p>Las cookies de marketing\/seguimiento son cookies, o cualquier otra forma de almacenamiento local, usadas para crear perfiles de usuario para mostrar publicidad o para hacer el seguimiento del usuario en esta web o en varias webs con fines de marketing similares.<\/p><h2>6. Cookies usadas<\/h2><div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Analytics<\/h3>\n\t\t<p>Estad\u00edsticas<\/p>\n\t\t<label for=\"cmplz_service_google-analytics\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-analytics<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-analytics\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-analytics\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos Google Analytics para estad\u00edsticas del sitio web.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/business.safety.google\/privacy\/\">pol\u00edtica de privacidad de Google Analytics<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estad\u00edsticas<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">_ga<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">_gid<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">_gat<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">_gat_gtag_UA_*<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">_ga_*<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WordPress<\/h3>\n\t\t<p>Estad\u00edsticas<\/p>\n\t\t<label for=\"cmplz_service_wordpress\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wordpress<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wordpress\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wordpress\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos WordPress para website development.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Estos datos no se comparten con terceros.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estad\u00edsticas<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">wordpress_test_cookie<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">wp-settings-time-*<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">wp-settings-*<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">wordpress_logged_in_*<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">wp_lang<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">WP_PREFERENCES_USER_*<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">wpEmojiSettingsSupports<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Complianz<\/h3>\n\t\t<p>Estad\u00edsticas<\/p>\n\t\t<label for=\"cmplz_service_complianz\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service complianz<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_complianz\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"complianz\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos Complianz para cookie consent management.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Estos datos no se comparten con terceros.&nbsp;Para m\u00e1s informaci\u00f3n, por favor, lee la <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/complianz.io\/legal\/privacy-statement\/\">pol\u00edtica de privacidad de Complianz<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estad\u00edsticas<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">complianz_policy_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_stats<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">complianz_consent_status<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_marketing<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_policy_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_functional<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_statistics-anonymous<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_preferences<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_statistics<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_consent_status<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_choice<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_banner-status<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmplz_consented_services<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">365 d\u00edas<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WPML<\/h3>\n\t\t<p>Estad\u00edsticas<\/p>\n\t\t<label for=\"cmplz_service_wpml\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wpml<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wpml\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wpml\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos WPML para locale management.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Estos datos no se comparten con terceros.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estad\u00edsticas<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">wp-wpml_current_language<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Fonts<\/h3>\n\t\t<p>Estad\u00edsticas<\/p>\n\t\t<label for=\"cmplz_service_google-fonts\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-fonts<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-fonts\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-fonts\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos Google Fonts para display of webfonts.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">pol\u00edtica de privacidad de Google Fonts<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estad\u00edsticas<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">Google Fonts API<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Maps<\/h3>\n\t\t<p>Estad\u00edsticas<\/p>\n\t\t<label for=\"cmplz_service_google-maps\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-maps<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-maps\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-maps\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos Google Maps para maps display.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/business.safety.google\/privacy\/\">pol\u00edtica de privacidad de Google Maps<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estad\u00edsticas<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">Google Maps API<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>YouTube<\/h3>\n\t\t<p>Estad\u00edsticas<\/p>\n\t\t<label for=\"cmplz_service_youtube\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service youtube<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_youtube\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"youtube\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos YouTube para video display.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">pol\u00edtica de privacidad de YouTube<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estad\u00edsticas<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">GPS<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">VISITOR_INFO1_LIVE<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">YSC<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">PREF<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Slider Revolution<\/h3>\n\t\t<p>Prop\u00f3sito pendiente de investigaci\u00f3n<\/p>\n\t\t<label for=\"cmplz_service_slider-revolution\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service slider-revolution<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_slider-revolution\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"slider-revolution\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos Slider Revolution para website design.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Estos datos no se comparten con terceros.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Prop\u00f3sito pendiente de investigaci\u00f3n<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">rs6_library_pagination<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">rs6_overview_pagination<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google reCAPTCHA<\/h3>\n\t\t<p>Estad\u00edsticas<\/p>\n\t\t<label for=\"cmplz_service_google-recaptcha\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-recaptcha<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-recaptcha\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-recaptcha\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos Google reCAPTCHA para spam prevention.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">pol\u00edtica de privacidad de Google reCAPTCHA<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estad\u00edsticas<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">_grecaptcha<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">rc::c<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">rc::b<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">rc::a<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Wistia<\/h3>\n\t\t<p>Estad\u00edsticas<\/p>\n\t\t<label for=\"cmplz_service_wistia\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wistia<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wistia\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wistia\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p>Usamos Wistia para video display.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>Para m\u00e1s informaci\u00f3n, por favor, lee la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/wistia.com\/privacy\">pol\u00edtica de privacidad de Wistia<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estad\u00edsticas<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-*<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">wistia<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Varios<\/h3>\n\t\t<p>Estad\u00edsticas<\/p>\n\t\t<label for=\"cmplz_service_varios\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service varios<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_varios\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"varios\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Uso<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartir datos<\/h4>\n\t\t<p>El intercambio de datos est\u00e1 pendiente de investigaci\u00f3n<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estad\u00edsticas<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">AI_sentBuffer<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">AI_buffer<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">ai_user<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\">1 a\u00f1o<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\">Seguimiento de los visitantes en todos los sitios web<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Prop\u00f3sito pendiente de investigaci\u00f3n<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">ai_session<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">WP_DATA_USER_16<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">continueReview<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">9mms7jfc<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">22qt8kui<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">fibmekqw<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">tbk90yyv<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">61u4h10u<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">5t6wken1<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">kd799e8f<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">o1pr564h<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">wbfqi6y4<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">s1bgwkr1<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">r455j9t1<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">pzh6o248<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">r3hiy4gk<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">bg2fvyk3<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">5fw6fhgp<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">6pxg2bmh<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">n18to6yf<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">huo7ba84<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">upuq0p8o<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">wsr461tw<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">50utlbxh<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">4shmiyv7<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">0qfy42s8<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">gx71a45r<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">643crdcw<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">c8bjd6lg<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">5nyd00ih<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">j5xsco84<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">xra9l63y<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">pnyrnnko<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">1peeoadx<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">f2nve05n<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">oibwnt17<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">ylsbchyn<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">dwd8plio<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">gfjt8n2z<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">r8wm77us<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">7hmuhhqo<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">jol2pguv<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">9rif636g<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">k7d7bu29<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">k2bqe4w8<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">fq8qv1up<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">qrnfnqih<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">xgu7j4ts<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">mmv3vqps<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">cmtub0wd<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">s5c6fe75<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">bckd1euf<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">5jnc4slc<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">l4cpg8fl<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">k3dtnvwn<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">lvyv4pxf<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">im3mxfcd<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">wpml-available-translators-notice-dismissed<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">_lscache_vary<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">PHPSESSID<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nombre<\/h5>\n<\/div>\n<div class=\"name\">adobeCleanFontAdded<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducidad<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3n<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<\/div><h2>7. Consentimiento<\/h2><p>Cuando visites nuestra web por primera vez, te mostraremos una ventana emergente con una explicaci\u00f3n sobre las cookies. Tan pronto como hagas clic en \u00abGuardar preferencias\u00bb, aceptas que usemos las categor\u00edas de cookies y plugins que has seleccionado en la ventana emergente, tal y como se describe en esta pol\u00edtica de cookies. Puedes desactivar el uso de cookies a trav\u00e9s de tu navegador, pero, por favor, ten en cuenta que nuestra web puede dejar de funcionar correctamente.<\/p><p class=\"cmplz-subtitle\">7.1 Gestiona tus ajustes de consentimiento<\/p><div id=\"cmplz-manage-consent-container-nojavascript\">Has cargado la pol\u00edtica de cookies sin compatibilidad con JavaScript.&nbsp;En AMP, puedes utilizar el bot\u00f3n de gestionar el consentimiento en la parte inferior de la p\u00e1gina.<\/div><div id=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div><h2>8. Activaci\u00f3n\/desactivaci\u00f3n y borrado de cookies<\/h2><p>Puedes utilizar tu navegador de Internet para eliminar las cookies de forma autom\u00e1tica o manual. Tambi\u00e9n puedes especificar que ciertas cookies no pueden ser colocadas. Otra opci\u00f3n es cambiar los ajustes de tu navegador de Internet para que recibas un mensaje cada vez que se coloca una cookie. Para obtener m\u00e1s informaci\u00f3n sobre estas opciones, consulta las instrucciones de la secci\u00f3n \u00abAyuda\u00bb de tu navegador.<\/p><p>Ten en cuenta que nuestra web puede no funcionar correctamente si todas las cookies est\u00e1n desactivadas. Si borras las cookies de tu navegador, se volver\u00e1n a colocar despu\u00e9s de tu consentimiento cuando vuelvas a visitar nuestras webs.<\/p><h2>9. Tus derechos con respecto a los datos personales<\/h2><p>Tienes los siguientes derechos con respecto a tus datos personales:<\/p><ul>\n                    <li>Tiene derecho a saber por qu\u00e9 se necesitan tus datos personales, qu\u00e9 suceder\u00e1 con ellos y durante cu\u00e1nto tiempo se conservar\u00e1n.<\/li>\n                    <li>Derecho de acceso: tienes derecho a acceder a tus datos personales que conocemos.<\/li>\n                    <li>Derecho de rectificaci\u00f3n: tienes derecho a completar, rectificar, borrar o bloquear tus datos personales cuando lo desees.<\/li>\n                    <li>Si nos das tu consentimiento para procesar tus datos, tienes derecho a revocar dicho consentimiento y a que se eliminen tus datos personales.<\/li>\n                    <li>Derecho de cesi\u00f3n de tus datos: tienes derecho a solicitar todos tus datos personales al responsable del tratamiento y a transferirlos \u00edntegramente a otro responsable del tratamiento.<\/li>\n                    <li>Derecho de oposici\u00f3n: puedes oponerte al tratamiento de tus datos. Nosotros cumplimos con esto, a menos que existan motivos justificados para el procesamiento.<\/li>\n                <\/ul><p>Para ejercer estos derechos, por favor, contacta con nosotros. Por favor, consulta los detalles de contacto en la parte inferior de esta pol\u00edtica de cookies. Si tienes alguna queja sobre c\u00f3mo gestionamos tus datos, nos gustar\u00eda que nos la hicieras saber, pero tambi\u00e9n tienes derecho a enviar una queja a la autoridad supervisora (la autoridad de protecci\u00f3n de datos).<\/p><h2>10. Datos de contacto<\/h2><p>Para preguntas y\/o comentarios sobre nuestra pol\u00edtica de cookies y esta declaraci\u00f3n, por favor, contacta con nosotros usando los siguientes datos de contacto:<\/p><p><span class=\"cmplz-contact-organisation\">LIPOTRUE SL<\/span><br>\n                      <span class=\"cmplz-contact-address\">POL IND LES MARINES CALLE IMAGINACI\u00d3 12 08850, GAVA (BARCELONA)<\/span><br>\n                      <span class=\"cmplz-contact-country\">Espa\u00f1a<\/span><br>\n                      <span class=\"cmplz-contact-domain\">Web: <a href=\"https:\/\/lipotrue.com\/es\/\">https:\/\/lipotrue.com\/es\/<\/a><\/span><br>\n                      <span class=\"cmplz-contact-email\">Correo electr\u00f3nico: <span class=\"cmplz-obfuscate\">info@<span class=\"cmplz-fmail-domain\">&#101;x&#046;&#099;om<\/span>li&#112;o&#116;&#114;&#117;e&#046;com<\/span><\/span><br>\n                    <span class=\"cmplz-contact-telephone\">N\u00famero de tel\u00e9fono: (+34) 93 547 76 09<\/span><\/p><p>Esta pol\u00edtica de cookies se ha sincronizado con <a href=\"https:\/\/cookiedatabase.org\/\" target=\"_blank\">cookiedatabase.org<\/a> el abril 23, 2026.<\/p><\/div>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1552641277170{background-image: url(https:\/\/lipotrue.com\/wp-content\/uploads\/2019\/03\/area_privada_fondo05.jpg?id=1409) !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;4444&#8243; img_size=&#8221;full&#8221; alignment=&#8221;right&#8221; el_class=&#8221;iconos_lipotrue_web&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;3\/4&#8243;][vc_column_text] Pol\u00edtica de cookies Informaci\u00f3n conforme a la normativa sobre cookies[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1552490080810{margin-top: 25px !important;background-color: #ffffff !important;}&#8221;][vc_column width=&#8221;1\/4&#8243; css=&#8221;.vc_custom_1552461786365{margin-top: 30px !important;margin-bottom: 30px !important;padding-top: 0px !important;padding-right: 0px !important;padding-bottom: 0px !important;}&#8221; el_class=&#8221;tech_marine_texto&#8221;][vc_single_image image=&#8221;4179&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;right&#8221; css=&#8221;.vc_custom_1552646805723{margin-bottom: 10px !important;}&#8221; el_class=&#8221;.tech_piedefoto&#8221;][\/vc_column][vc_column width=&#8221;3\/4&#8243;][vc_column_text css=&#8221;.vc_custom_1571826372537{margin-bottom: 6px !important;}&#8221;] Pol\u00edtica de &#8230;<\/p>\n<p><a class=\"btn btn-primary read-more-link\" href=\"https:\/\/lipotrue.com\/es\/politica-de-cookies\/\">Read More &rarr;<\/a><\/p>\n","protected":false},"author":76,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/pagebuilder-page.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-8596","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de cookies - Lipotrue<\/title>\n<meta name=\"description\" content=\"Informaci\u00f3n conforme a la normativa sobre cookies\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lipotrue.com\/es\/politica-de-cookies\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de cookies - Lipotrue\" \/>\n<meta property=\"og:description\" content=\"Informaci\u00f3n conforme a la normativa sobre cookies\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lipotrue.com\/es\/politica-de-cookies\/\" \/>\n<meta property=\"og:site_name\" content=\"Lipotrue\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-24T12:25:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lipotrue.com\\\/es\\\/politica-de-cookies\\\/\",\"url\":\"https:\\\/\\\/lipotrue.com\\\/es\\\/politica-de-cookies\\\/\",\"name\":\"Pol\u00edtica de cookies - Lipotrue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lipotrue.com\\\/es\\\/#website\"},\"datePublished\":\"2021-02-24T12:24:46+00:00\",\"dateModified\":\"2021-02-24T12:25:53+00:00\",\"description\":\"Informaci\u00f3n conforme a la normativa sobre cookies\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lipotrue.com\\\/es\\\/politica-de-cookies\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lipotrue.com\\\/es\\\/politica-de-cookies\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lipotrue.com\\\/es\\\/politica-de-cookies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lipotrue.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de cookies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lipotrue.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/lipotrue.com\\\/es\\\/\",\"name\":\"Lipotrue\",\"description\":\"Cosmetic active ingredients\",\"publisher\":{\"@id\":\"https:\\\/\\\/lipotrue.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lipotrue.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lipotrue.com\\\/es\\\/#organization\",\"name\":\"Lipotrue\",\"url\":\"https:\\\/\\\/lipotrue.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lipotrue.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lipotrue.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo-lipotrue-big.png\",\"contentUrl\":\"https:\\\/\\\/lipotrue.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo-lipotrue-big.png\",\"width\":328,\"height\":80,\"caption\":\"Lipotrue\"},\"image\":{\"@id\":\"https:\\\/\\\/lipotrue.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de cookies - Lipotrue","description":"Informaci\u00f3n conforme a la normativa sobre cookies","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lipotrue.com\/es\/politica-de-cookies\/","og_locale":"es_ES","og_type":"article","og_title":"Pol\u00edtica de cookies - Lipotrue","og_description":"Informaci\u00f3n conforme a la normativa sobre cookies","og_url":"https:\/\/lipotrue.com\/es\/politica-de-cookies\/","og_site_name":"Lipotrue","article_modified_time":"2021-02-24T12:25:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lipotrue.com\/es\/politica-de-cookies\/","url":"https:\/\/lipotrue.com\/es\/politica-de-cookies\/","name":"Pol\u00edtica de cookies - Lipotrue","isPartOf":{"@id":"https:\/\/lipotrue.com\/es\/#website"},"datePublished":"2021-02-24T12:24:46+00:00","dateModified":"2021-02-24T12:25:53+00:00","description":"Informaci\u00f3n conforme a la normativa sobre cookies","breadcrumb":{"@id":"https:\/\/lipotrue.com\/es\/politica-de-cookies\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lipotrue.com\/es\/politica-de-cookies\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lipotrue.com\/es\/politica-de-cookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lipotrue.com\/es\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de cookies"}]},{"@type":"WebSite","@id":"https:\/\/lipotrue.com\/es\/#website","url":"https:\/\/lipotrue.com\/es\/","name":"Lipotrue","description":"Cosmetic active ingredients","publisher":{"@id":"https:\/\/lipotrue.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lipotrue.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lipotrue.com\/es\/#organization","name":"Lipotrue","url":"https:\/\/lipotrue.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lipotrue.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/lipotrue.com\/wp-content\/uploads\/2019\/03\/logo-lipotrue-big.png","contentUrl":"https:\/\/lipotrue.com\/wp-content\/uploads\/2019\/03\/logo-lipotrue-big.png","width":328,"height":80,"caption":"Lipotrue"},"image":{"@id":"https:\/\/lipotrue.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lipotrue.com\/es\/wp-json\/wp\/v2\/pages\/8596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lipotrue.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lipotrue.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lipotrue.com\/es\/wp-json\/wp\/v2\/users\/76"}],"replies":[{"embeddable":true,"href":"https:\/\/lipotrue.com\/es\/wp-json\/wp\/v2\/comments?post=8596"}],"version-history":[{"count":0,"href":"https:\/\/lipotrue.com\/es\/wp-json\/wp\/v2\/pages\/8596\/revisions"}],"wp:attachment":[{"href":"https:\/\/lipotrue.com\/es\/wp-json\/wp\/v2\/media?parent=8596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}